{"id":422,"date":"2017-10-18T17:10:21","date_gmt":"2017-10-18T15:10:21","guid":{"rendered":"http:\/\/chiomedoro.com\/?page_id=422"},"modified":"2017-12-12T21:37:12","modified_gmt":"2017-12-12T20:37:12","slug":"giona","status":"publish","type":"page","link":"https:\/\/chiomedoro.com\/index.php\/medias\/photos\/giona\/","title":{"rendered":"Giona"},"content":{"rendered":"<div class=\"tiled-gallery type-rectangular tiled-gallery-unresized\" data-original-width=\"720\" data-carousel-extra='{&quot;blog_id&quot;:1,&quot;permalink&quot;:&quot;https:\\\/\\\/chiomedoro.com\\\/index.php\\\/medias\\\/photos\\\/giona\\\/&quot;,&quot;likes_blog_id&quot;:136980409}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 720px; height: 574px;\" data-original-width=\"720\" data-original-height=\"574\" > <div class=\"gallery-group images-3\" style=\"width: 288px; height: 574px;\" data-original-width=\"288\" data-original-height=\"574\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/chiomedoro_giona_18\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"284\"> <meta itemprop=\"height\" content=\"189\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"378\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_18.jpg\" data-orig-size=\"620,412\" data-comments-opened=\"\" data-image-title=\"ChiomeDOro_Giona_18\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_18.jpg?fit=300%2C199&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_18.jpg?fit=620%2C412&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_18.jpg?w=284&#038;h=189&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_18.jpg?w=620&amp;ssl=1 620w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_18.jpg?resize=300%2C199&amp;ssl=1 300w\" width=\"284\" height=\"189\" loading=\"lazy\" data-original-width=\"284\" data-original-height=\"189\" itemprop=\"http:\/\/schema.org\/image\" title=\"ChiomeDOro_Giona_18\" alt=\"ChiomeDOro_Giona_18\" style=\"width: 284px; height: 189px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/chiomedoro_giona_07\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"284\"> <meta itemprop=\"height\" content=\"186\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"367\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_07.jpg\" data-orig-size=\"750,492\" data-comments-opened=\"\" data-image-title=\"ChiomeDOro_Giona_07\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_07.jpg?fit=300%2C197&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_07.jpg?fit=720%2C472&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_07.jpg?w=284&#038;h=186&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_07.jpg?w=750&amp;ssl=1 750w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_07.jpg?resize=300%2C197&amp;ssl=1 300w\" width=\"284\" height=\"186\" loading=\"lazy\" data-original-width=\"284\" data-original-height=\"186\" itemprop=\"http:\/\/schema.org\/image\" title=\"ChiomeDOro_Giona_07\" alt=\"\u00a9Jacques Philippet\" style=\"width: 284px; height: 186px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> \u00a9Jacques Philippet <\/div> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/chiomedoro_giona_08\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"284\"> <meta itemprop=\"height\" content=\"187\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"368\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_08.jpg\" data-orig-size=\"750,494\" data-comments-opened=\"\" data-image-title=\"ChiomeDOro_Giona_08\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_08.jpg?fit=300%2C198&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_08.jpg?fit=720%2C474&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_08.jpg?w=284&#038;h=187&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_08.jpg?w=750&amp;ssl=1 750w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_08.jpg?resize=300%2C198&amp;ssl=1 300w\" width=\"284\" height=\"187\" loading=\"lazy\" data-original-width=\"284\" data-original-height=\"187\" itemprop=\"http:\/\/schema.org\/image\" title=\"ChiomeDOro_Giona_08\" alt=\"\u00a9Jacques Philippet\" style=\"width: 284px; height: 187px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> \u00a9Jacques Philippet <\/div> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 432px; height: 574px;\" data-original-width=\"432\" data-original-height=\"574\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/chiomedoro_giona_15\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"428\"> <meta itemprop=\"height\" content=\"570\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"375\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_15.jpg\" data-orig-size=\"1200,1600\" data-comments-opened=\"\" data-image-title=\"ChiomeDOro_Giona_15\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_15.jpg?fit=225%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_15.jpg?fit=720%2C960&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_15.jpg?w=428&#038;h=570&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_15.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_15.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_15.jpg?resize=768%2C1024&amp;ssl=1 768w\" width=\"428\" height=\"570\" loading=\"lazy\" data-original-width=\"428\" data-original-height=\"570\" itemprop=\"http:\/\/schema.org\/image\" title=\"ChiomeDOro_Giona_15\" alt=\"\u00a9B.Archinard\" style=\"width: 428px; height: 570px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> \u00a9B.Archinard <\/div> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 720px; height: 304px;\" data-original-width=\"720\" data-original-height=\"304\" > <div class=\"gallery-group images-1\" style=\"width: 278px; height: 304px;\" data-original-width=\"278\" data-original-height=\"304\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/chiomedoro_giona_14\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"274\"> <meta itemprop=\"height\" content=\"300\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"374\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_14.jpg\" data-orig-size=\"1457,1600\" data-comments-opened=\"\" data-image-title=\"ChiomeDOro_Giona_14\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_14.jpg?fit=273%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_14.jpg?fit=720%2C791&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_14.jpg?w=274&#038;h=300&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_14.jpg?w=1457&amp;ssl=1 1457w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_14.jpg?resize=273%2C300&amp;ssl=1 273w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_14.jpg?resize=768%2C843&amp;ssl=1 768w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_14.jpg?resize=932%2C1024&amp;ssl=1 932w\" width=\"274\" height=\"300\" loading=\"lazy\" data-original-width=\"274\" data-original-height=\"300\" itemprop=\"http:\/\/schema.org\/image\" title=\"ChiomeDOro_Giona_14\" alt=\"ChiomeDOro_Giona_14\" style=\"width: 274px; height: 300px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 213px; height: 304px;\" data-original-width=\"213\" data-original-height=\"304\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/chiomedoro_giona_30\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"209\"> <meta itemprop=\"height\" content=\"157\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"390\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_30.jpg\" data-orig-size=\"1600,1200\" data-comments-opened=\"\" data-image-title=\"ChiomeDOro_Giona_30\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_30.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_30.jpg?fit=720%2C540&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_30.jpg?w=209&#038;h=157&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_30.jpg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_30.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_30.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_30.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_30.jpg?w=1440&amp;ssl=1 1440w\" width=\"209\" height=\"157\" loading=\"lazy\" data-original-width=\"209\" data-original-height=\"157\" itemprop=\"http:\/\/schema.org\/image\" title=\"ChiomeDOro_Giona_30\" alt=\"ChiomeDOro_Giona_30\" style=\"width: 209px; height: 157px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/chiomedoro_giona_21\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"209\"> <meta itemprop=\"height\" content=\"139\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"381\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_21.jpg\" data-orig-size=\"640,426\" data-comments-opened=\"\" data-image-title=\"ChiomeDOro_Giona_21\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_21.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_21.jpg?fit=640%2C426&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_21.jpg?w=209&#038;h=139&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_21.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_21.jpg?resize=300%2C200&amp;ssl=1 300w\" width=\"209\" height=\"139\" loading=\"lazy\" data-original-width=\"209\" data-original-height=\"139\" itemprop=\"http:\/\/schema.org\/image\" title=\"ChiomeDOro_Giona_21\" alt=\"ChiomeDOro_Giona_21\" style=\"width: 209px; height: 139px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 229px; height: 304px;\" data-original-width=\"229\" data-original-height=\"304\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/chiomedoro_giona_05\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"225\"> <meta itemprop=\"height\" content=\"300\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"365\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_05.jpg\" data-orig-size=\"1200,1600\" data-comments-opened=\"\" data-image-title=\"ChiomeDOro_Giona_05\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_05.jpg?fit=225%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_05.jpg?fit=720%2C960&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_05.jpg?w=225&#038;h=300&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_05.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_05.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_05.jpg?resize=768%2C1024&amp;ssl=1 768w\" width=\"225\" height=\"300\" loading=\"lazy\" data-original-width=\"225\" data-original-height=\"300\" itemprop=\"http:\/\/schema.org\/image\" title=\"ChiomeDOro_Giona_05\" alt=\"ChiomeDOro_Giona_05\" style=\"width: 225px; height: 300px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 720px; height: 471px;\" data-original-width=\"720\" data-original-height=\"471\" > <div class=\"gallery-group images-1\" style=\"width: 354px; height: 471px;\" data-original-width=\"354\" data-original-height=\"471\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/chiomedoro_giona_16\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"350\"> <meta itemprop=\"height\" content=\"467\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"376\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_16.jpg\" data-orig-size=\"1200,1600\" data-comments-opened=\"\" data-image-title=\"ChiomeDOro_Giona_16\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_16.jpg?fit=225%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_16.jpg?fit=720%2C960&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_16.jpg?w=350&#038;h=467&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_16.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_16.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_16.jpg?resize=768%2C1024&amp;ssl=1 768w\" width=\"350\" height=\"467\" loading=\"lazy\" data-original-width=\"350\" data-original-height=\"467\" itemprop=\"http:\/\/schema.org\/image\" title=\"ChiomeDOro_Giona_16\" alt=\"\u00a9B.Archinard\" style=\"width: 350px; height: 467px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> \u00a9B.Archinard <\/div> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 366px; height: 471px;\" data-original-width=\"366\" data-original-height=\"471\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/chiomedoro_giona_28\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"362\"> <meta itemprop=\"height\" content=\"467\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"388\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_28.jpg\" data-orig-size=\"1241,1600\" data-comments-opened=\"\" data-image-title=\"ChiomeDOro_Giona_28\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_28.jpg?fit=233%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_28.jpg?fit=720%2C929&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_28.jpg?w=362&#038;h=467&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_28.jpg?w=1241&amp;ssl=1 1241w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_28.jpg?resize=233%2C300&amp;ssl=1 233w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_28.jpg?resize=768%2C990&amp;ssl=1 768w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_28.jpg?resize=794%2C1024&amp;ssl=1 794w\" width=\"362\" height=\"467\" loading=\"lazy\" data-original-width=\"362\" data-original-height=\"467\" itemprop=\"http:\/\/schema.org\/image\" title=\"ChiomeDOro_Giona_28\" alt=\"ChiomeDOro_Giona_28\" style=\"width: 362px; height: 467px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 720px; height: 330px;\" data-original-width=\"720\" data-original-height=\"330\" > <div class=\"gallery-group images-1\" style=\"width: 499px; height: 330px;\" data-original-width=\"499\" data-original-height=\"330\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/chiomedoro_giona_09\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"495\"> <meta itemprop=\"height\" content=\"326\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"369\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_09.jpg\" data-orig-size=\"750,494\" data-comments-opened=\"\" data-image-title=\"ChiomeDOro_Giona_09\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_09.jpg?fit=300%2C198&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_09.jpg?fit=720%2C474&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_09.jpg?w=495&#038;h=326&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_09.jpg?w=750&amp;ssl=1 750w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_09.jpg?resize=300%2C198&amp;ssl=1 300w\" width=\"495\" height=\"326\" loading=\"lazy\" data-original-width=\"495\" data-original-height=\"326\" itemprop=\"http:\/\/schema.org\/image\" title=\"ChiomeDOro_Giona_09\" alt=\"\u00a9Jacques Philippet\" style=\"width: 495px; height: 326px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> \u00a9Jacques Philippet <\/div> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 221px; height: 330px;\" data-original-width=\"221\" data-original-height=\"330\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/chiomedoro_giona_26\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"217\"> <meta itemprop=\"height\" content=\"326\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"386\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_26.jpg\" data-orig-size=\"1063,1600\" data-comments-opened=\"\" data-image-title=\"ChiomeDOro_Giona_26\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_26.jpg?fit=199%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_26.jpg?fit=680%2C1024&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_26.jpg?w=217&#038;h=326&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_26.jpg?w=1063&amp;ssl=1 1063w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_26.jpg?resize=199%2C300&amp;ssl=1 199w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_26.jpg?resize=768%2C1156&amp;ssl=1 768w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_26.jpg?resize=680%2C1024&amp;ssl=1 680w\" width=\"217\" height=\"326\" loading=\"lazy\" data-original-width=\"217\" data-original-height=\"326\" itemprop=\"http:\/\/schema.org\/image\" title=\"ChiomeDOro_Giona_26\" alt=\"ChiomeDOro_Giona_26\" style=\"width: 217px; height: 326px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 720px; height: 480px;\" data-original-width=\"720\" data-original-height=\"480\" > <div class=\"gallery-group images-1\" style=\"width: 361px; height: 480px;\" data-original-width=\"361\" data-original-height=\"480\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/chiomedoro_giona_04\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"357\"> <meta itemprop=\"height\" content=\"476\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"364\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_04.jpg\" data-orig-size=\"1200,1600\" data-comments-opened=\"\" data-image-title=\"ChiomeDOro_Giona_04\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_04.jpg?fit=225%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_04.jpg?fit=720%2C960&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_04.jpg?w=357&#038;h=476&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_04.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_04.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_04.jpg?resize=768%2C1024&amp;ssl=1 768w\" width=\"357\" height=\"476\" loading=\"lazy\" data-original-width=\"357\" data-original-height=\"476\" itemprop=\"http:\/\/schema.org\/image\" title=\"ChiomeDOro_Giona_04\" alt=\"ChiomeDOro_Giona_04\" style=\"width: 357px; height: 476px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 359px; height: 480px;\" data-original-width=\"359\" data-original-height=\"480\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/index.php\/medias\/photos\/giona\/_dsc6609_chiome_doro_giona_fest_amb_01102016__bertrand_pichene-ccr_ambronay\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"355\"> <meta itemprop=\"height\" content=\"235\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"768\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/12\/DSC6609_Chiome_dOro_Giona_Fest_Amb_01102016_\u00a9_Bertrand_PICHENE-CCR_Ambronay.jpg\" data-orig-size=\"4928,3264\" data-comments-opened=\"1\" data-image-title=\"_DSC6609_Chiome_dOro_Giona_Fest_Amb_01102016_\u00a9_Bertrand_PICHENE-CCR_Ambronay\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/12\/DSC6609_Chiome_dOro_Giona_Fest_Amb_01102016_%C2%A9_Bertrand_PICHENE-CCR_Ambronay.jpg?fit=300%2C199&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/12\/DSC6609_Chiome_dOro_Giona_Fest_Amb_01102016_%C2%A9_Bertrand_PICHENE-CCR_Ambronay.jpg?fit=720%2C477&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/12\/DSC6609_Chiome_dOro_Giona_Fest_Amb_01102016_%C2%A9_Bertrand_PICHENE-CCR_Ambronay.jpg?w=355&#038;h=235&#038;ssl=1\" width=\"355\" height=\"235\" loading=\"lazy\" data-original-width=\"355\" data-original-height=\"235\" itemprop=\"http:\/\/schema.org\/image\" title=\"_DSC6609_Chiome_dOro_Giona_Fest_Amb_01102016_\u00a9_Bertrand_PICHENE-CCR_Ambronay\" alt=\"Ambronay 2016 \u00a9Bertrand Pich\u00e8ne\" style=\"width: 355px; height: 235px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Ambronay 2016 \u00a9Bertrand Pich\u00e8ne <\/div> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/chiomedoro_giona_11\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"355\"> <meta itemprop=\"height\" content=\"237\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"371\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_11.jpg\" data-orig-size=\"750,500\" data-comments-opened=\"\" data-image-title=\"ChiomeDOro_Giona_11\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_11.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_11.jpg?fit=720%2C480&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_11.jpg?w=355&#038;h=237&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_11.jpg?w=750&amp;ssl=1 750w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_11.jpg?resize=300%2C200&amp;ssl=1 300w\" width=\"355\" height=\"237\" loading=\"lazy\" data-original-width=\"355\" data-original-height=\"237\" itemprop=\"http:\/\/schema.org\/image\" title=\"ChiomeDOro_Giona_11\" alt=\"\u00a9Jacques Philippet\" style=\"width: 355px; height: 237px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> \u00a9Jacques Philippet <\/div> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 720px; height: 245px;\" data-original-width=\"720\" data-original-height=\"245\" > <div class=\"gallery-group images-1\" style=\"width: 185px; height: 245px;\" data-original-width=\"185\" data-original-height=\"245\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/chiomedoro_giona_01\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"181\"> <meta itemprop=\"height\" content=\"241\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"361\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_01.jpg\" data-orig-size=\"1200,1600\" data-comments-opened=\"\" data-image-title=\"ChiomeDOro_Giona_01\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_01.jpg?fit=225%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_01.jpg?fit=720%2C960&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_01.jpg?w=181&#038;h=241&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_01.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_01.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_01.jpg?resize=768%2C1024&amp;ssl=1 768w\" width=\"181\" height=\"241\" loading=\"lazy\" data-original-width=\"181\" data-original-height=\"241\" itemprop=\"http:\/\/schema.org\/image\" title=\"ChiomeDOro_Giona_01\" alt=\"ChiomeDOro_Giona_01\" style=\"width: 181px; height: 241px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 165px; height: 245px;\" data-original-width=\"165\" data-original-height=\"245\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/chiomedoro_giona_13\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"161\"> <meta itemprop=\"height\" content=\"241\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"373\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_13.jpg\" data-orig-size=\"426,640\" data-comments-opened=\"\" data-image-title=\"ChiomeDOro_Giona_13\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_13.jpg?fit=200%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_13.jpg?fit=426%2C640&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_13.jpg?w=161&#038;h=241&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_13.jpg?w=426&amp;ssl=1 426w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_13.jpg?resize=200%2C300&amp;ssl=1 200w\" width=\"161\" height=\"241\" loading=\"lazy\" data-original-width=\"161\" data-original-height=\"241\" itemprop=\"http:\/\/schema.org\/image\" title=\"ChiomeDOro_Giona_13\" alt=\"ChiomeDOro_Giona_13\" style=\"width: 161px; height: 241px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 185px; height: 245px;\" data-original-width=\"185\" data-original-height=\"245\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/chiomedoro_giona_17\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"181\"> <meta itemprop=\"height\" content=\"241\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"377\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_17.jpg\" data-orig-size=\"1200,1600\" data-comments-opened=\"\" data-image-title=\"ChiomeDOro_Giona_17\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_17.jpg?fit=225%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_17.jpg?fit=720%2C960&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_17.jpg?w=181&#038;h=241&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_17.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_17.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_17.jpg?resize=768%2C1024&amp;ssl=1 768w\" width=\"181\" height=\"241\" loading=\"lazy\" data-original-width=\"181\" data-original-height=\"241\" itemprop=\"http:\/\/schema.org\/image\" title=\"ChiomeDOro_Giona_17\" alt=\"ChiomeDOro_Giona_17\" style=\"width: 181px; height: 241px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 185px; height: 245px;\" data-original-width=\"185\" data-original-height=\"245\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/chiomedoro_giona_03\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"181\"> <meta itemprop=\"height\" content=\"241\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"363\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_03.jpg\" data-orig-size=\"1200,1600\" data-comments-opened=\"\" data-image-title=\"ChiomeDOro_Giona_03\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_03.jpg?fit=225%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_03.jpg?fit=720%2C960&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_03.jpg?w=181&#038;h=241&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_03.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_03.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_03.jpg?resize=768%2C1024&amp;ssl=1 768w\" width=\"181\" height=\"241\" loading=\"lazy\" data-original-width=\"181\" data-original-height=\"241\" itemprop=\"http:\/\/schema.org\/image\" title=\"ChiomeDOro_Giona_03\" alt=\"ChiomeDOro_Giona_03\" style=\"width: 181px; height: 241px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 720px; height: 332px;\" data-original-width=\"720\" data-original-height=\"332\" > <div class=\"gallery-group images-1\" style=\"width: 497px; height: 332px;\" data-original-width=\"497\" data-original-height=\"332\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/chiomedoro_giona_19\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"493\"> <meta itemprop=\"height\" content=\"328\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"379\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_19.jpg\" data-orig-size=\"640,426\" data-comments-opened=\"\" data-image-title=\"ChiomeDOro_Giona_19\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_19.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_19.jpg?fit=640%2C426&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_19.jpg?w=493&#038;h=328&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_19.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_19.jpg?resize=300%2C200&amp;ssl=1 300w\" width=\"493\" height=\"328\" loading=\"lazy\" data-original-width=\"493\" data-original-height=\"328\" itemprop=\"http:\/\/schema.org\/image\" title=\"ChiomeDOro_Giona_19\" alt=\"ChiomeDOro_Giona_19\" style=\"width: 493px; height: 328px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 223px; height: 332px;\" data-original-width=\"223\" data-original-height=\"332\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/chiomedoro_giona_22\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"219\"> <meta itemprop=\"height\" content=\"328\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"382\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_22.jpg\" data-orig-size=\"426,640\" data-comments-opened=\"\" data-image-title=\"ChiomeDOro_Giona_22\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_22.jpg?fit=200%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_22.jpg?fit=426%2C640&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_22.jpg?w=219&#038;h=328&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_22.jpg?w=426&amp;ssl=1 426w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_22.jpg?resize=200%2C300&amp;ssl=1 200w\" width=\"219\" height=\"328\" loading=\"lazy\" data-original-width=\"219\" data-original-height=\"328\" itemprop=\"http:\/\/schema.org\/image\" title=\"ChiomeDOro_Giona_22\" alt=\"ChiomeDOro_Giona_22\" style=\"width: 219px; height: 328px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 720px; height: 345px;\" data-original-width=\"720\" data-original-height=\"345\" > <div class=\"gallery-group images-1\" style=\"width: 230px; height: 345px;\" data-original-width=\"230\" data-original-height=\"345\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/index.php\/medias\/photos\/giona\/_dsc6488_chiome_doro_giona_fest_amb_01102016__bertrand_pichene-ccr_ambronay\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"226\"> <meta itemprop=\"height\" content=\"341\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"765\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/12\/DSC6488_Chiome_dOro_Giona_Fest_Amb_01102016_\u00a9_Bertrand_PICHENE-CCR_Ambronay.jpg\" data-orig-size=\"3264,4928\" data-comments-opened=\"1\" data-image-title=\"_DSC6488_Chiome_dOro_Giona_Fest_Amb_01102016_\u00a9_Bertrand_PICHENE-CCR_Ambronay\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/12\/DSC6488_Chiome_dOro_Giona_Fest_Amb_01102016_%C2%A9_Bertrand_PICHENE-CCR_Ambronay.jpg?fit=199%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/12\/DSC6488_Chiome_dOro_Giona_Fest_Amb_01102016_%C2%A9_Bertrand_PICHENE-CCR_Ambronay.jpg?fit=678%2C1024&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/12\/DSC6488_Chiome_dOro_Giona_Fest_Amb_01102016_%C2%A9_Bertrand_PICHENE-CCR_Ambronay.jpg?w=226&#038;h=341&#038;ssl=1\" width=\"226\" height=\"341\" loading=\"lazy\" data-original-width=\"226\" data-original-height=\"341\" itemprop=\"http:\/\/schema.org\/image\" title=\"_DSC6488_Chiome_dOro_Giona_Fest_Amb_01102016_\u00a9_Bertrand_PICHENE-CCR_Ambronay\" alt=\"Ambronay 2016 \u00a9Bertrand Pich\u00e8ne\" style=\"width: 226px; height: 341px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Ambronay 2016 \u00a9Bertrand Pich\u00e8ne <\/div> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 260px; height: 345px;\" data-original-width=\"260\" data-original-height=\"345\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/chiomedoro_giona_06\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"256\"> <meta itemprop=\"height\" content=\"341\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"366\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_06.jpg\" data-orig-size=\"1200,1600\" data-comments-opened=\"\" data-image-title=\"ChiomeDOro_Giona_06\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_06.jpg?fit=225%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_06.jpg?fit=720%2C960&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_06.jpg?w=256&#038;h=341&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_06.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_06.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_06.jpg?resize=768%2C1024&amp;ssl=1 768w\" width=\"256\" height=\"341\" loading=\"lazy\" data-original-width=\"256\" data-original-height=\"341\" itemprop=\"http:\/\/schema.org\/image\" title=\"ChiomeDOro_Giona_06\" alt=\"ChiomeDOro_Giona_06\" style=\"width: 256px; height: 341px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 230px; height: 345px;\" data-original-width=\"230\" data-original-height=\"345\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/chiomedoro_giona_25\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"226\"> <meta itemprop=\"height\" content=\"341\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"385\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_25.jpg\" data-orig-size=\"1063,1600\" data-comments-opened=\"\" data-image-title=\"ChiomeDOro_Giona_25\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_25.jpg?fit=199%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_25.jpg?fit=680%2C1024&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_25.jpg?w=226&#038;h=341&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_25.jpg?w=1063&amp;ssl=1 1063w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_25.jpg?resize=199%2C300&amp;ssl=1 199w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_25.jpg?resize=768%2C1156&amp;ssl=1 768w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_25.jpg?resize=680%2C1024&amp;ssl=1 680w\" width=\"226\" height=\"341\" loading=\"lazy\" data-original-width=\"226\" data-original-height=\"341\" itemprop=\"http:\/\/schema.org\/image\" title=\"ChiomeDOro_Giona_25\" alt=\"ChiomeDOro_Giona_25\" style=\"width: 226px; height: 341px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 720px; height: 320px;\" data-original-width=\"720\" data-original-height=\"320\" > <div class=\"gallery-group images-1\" style=\"width: 479px; height: 320px;\" data-original-width=\"479\" data-original-height=\"320\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/chiomedoro_giona_23\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"475\"> <meta itemprop=\"height\" content=\"316\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"383\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_23.jpg\" data-orig-size=\"1600,1063\" data-comments-opened=\"\" data-image-title=\"ChiomeDOro_Giona_23\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_23.jpg?fit=300%2C199&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_23.jpg?fit=720%2C478&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_23.jpg?w=475&#038;h=316&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_23.jpg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_23.jpg?resize=300%2C199&amp;ssl=1 300w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_23.jpg?resize=768%2C510&amp;ssl=1 768w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_23.jpg?resize=1024%2C680&amp;ssl=1 1024w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_23.jpg?w=1440&amp;ssl=1 1440w\" width=\"475\" height=\"316\" loading=\"lazy\" data-original-width=\"475\" data-original-height=\"316\" itemprop=\"http:\/\/schema.org\/image\" title=\"ChiomeDOro_Giona_23\" alt=\"ChiomeDOro_Giona_23\" style=\"width: 475px; height: 316px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 241px; height: 320px;\" data-original-width=\"241\" data-original-height=\"320\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/chiomedoro_giona_02\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"237\"> <meta itemprop=\"height\" content=\"316\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"362\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_02.jpg\" data-orig-size=\"1200,1600\" data-comments-opened=\"\" data-image-title=\"ChiomeDOro_Giona_02\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_02.jpg?fit=225%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_02.jpg?fit=720%2C960&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_02.jpg?w=237&#038;h=316&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_02.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_02.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_02.jpg?resize=768%2C1024&amp;ssl=1 768w\" width=\"237\" height=\"316\" loading=\"lazy\" data-original-width=\"237\" data-original-height=\"316\" itemprop=\"http:\/\/schema.org\/image\" title=\"ChiomeDOro_Giona_02\" alt=\"ChiomeDOro_Giona_02\" style=\"width: 237px; height: 316px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 720px; height: 585px;\" data-original-width=\"720\" data-original-height=\"585\" > <div class=\"gallery-group images-1\" style=\"width: 439px; height: 585px;\" data-original-width=\"439\" data-original-height=\"585\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/chiomedoro_giona_24\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"435\"> <meta itemprop=\"height\" content=\"581\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"384\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_24.jpg\" data-orig-size=\"1200,1600\" data-comments-opened=\"\" data-image-title=\"ChiomeDOro_Giona_24\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_24.jpg?fit=225%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_24.jpg?fit=720%2C960&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_24.jpg?w=435&#038;h=581&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_24.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_24.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_24.jpg?resize=768%2C1024&amp;ssl=1 768w\" width=\"435\" height=\"581\" loading=\"lazy\" data-original-width=\"435\" data-original-height=\"581\" itemprop=\"http:\/\/schema.org\/image\" title=\"ChiomeDOro_Giona_24\" alt=\"ChiomeDOro_Giona_24\" style=\"width: 435px; height: 581px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-3\" style=\"width: 281px; height: 585px;\" data-original-width=\"281\" data-original-height=\"585\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/chiomedoro_giona_10\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"277\"> <meta itemprop=\"height\" content=\"182\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"370\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_10.jpg\" data-orig-size=\"750,494\" data-comments-opened=\"\" data-image-title=\"ChiomeDOro_Giona_10\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_10.jpg?fit=300%2C198&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_10.jpg?fit=720%2C474&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_10.jpg?w=277&#038;h=182&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_10.jpg?w=750&amp;ssl=1 750w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_10.jpg?resize=300%2C198&amp;ssl=1 300w\" width=\"277\" height=\"182\" loading=\"lazy\" data-original-width=\"277\" data-original-height=\"182\" itemprop=\"http:\/\/schema.org\/image\" title=\"ChiomeDOro_Giona_10\" alt=\"\u00a9Jacques Philippet\" style=\"width: 277px; height: 182px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> \u00a9Jacques Philippet <\/div> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/chiomedoro_giona_31\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"277\"> <meta itemprop=\"height\" content=\"208\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"391\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_31.jpg\" data-orig-size=\"2048,1536\" data-comments-opened=\"\" data-image-title=\"ChiomeDOro_Giona_31\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_31.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_31.jpg?fit=720%2C540&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_31.jpg?w=277&#038;h=208&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_31.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_31.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_31.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_31.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_31.jpg?w=1440&amp;ssl=1 1440w\" width=\"277\" height=\"208\" loading=\"lazy\" data-original-width=\"277\" data-original-height=\"208\" itemprop=\"http:\/\/schema.org\/image\" title=\"ChiomeDOro_Giona_31\" alt=\"\u00a9B.Archinard\" style=\"width: 277px; height: 208px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> \u00a9B.Archinard <\/div> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/index.php\/medias\/photos\/giona\/_dsc6567_chiome_doro_giona_fest_amb_01102016__bertrand_pichene-ccr_ambronay\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"277\"> <meta itemprop=\"height\" content=\"183\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"767\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/12\/DSC6567_Chiome_dOro_Giona_Fest_Amb_01102016_\u00a9_Bertrand_PICHENE-CCR_Ambronay.jpg\" data-orig-size=\"4928,3264\" data-comments-opened=\"1\" data-image-title=\"_DSC6567_Chiome_dOro_Giona_Fest_Amb_01102016_\u00a9_Bertrand_PICHENE-CCR_Ambronay\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/12\/DSC6567_Chiome_dOro_Giona_Fest_Amb_01102016_%C2%A9_Bertrand_PICHENE-CCR_Ambronay.jpg?fit=300%2C199&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/12\/DSC6567_Chiome_dOro_Giona_Fest_Amb_01102016_%C2%A9_Bertrand_PICHENE-CCR_Ambronay.jpg?fit=720%2C477&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/12\/DSC6567_Chiome_dOro_Giona_Fest_Amb_01102016_%C2%A9_Bertrand_PICHENE-CCR_Ambronay.jpg?w=277&#038;h=183&#038;ssl=1\" width=\"277\" height=\"183\" loading=\"lazy\" data-original-width=\"277\" data-original-height=\"183\" itemprop=\"http:\/\/schema.org\/image\" title=\"_DSC6567_Chiome_dOro_Giona_Fest_Amb_01102016_\u00a9_Bertrand_PICHENE-CCR_Ambronay\" alt=\"Ambronay 2016 \u00a9Bertrand Pich\u00e8ne\" style=\"width: 277px; height: 183px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Ambronay 2016 \u00a9Bertrand Pich\u00e8ne <\/div> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 720px; height: 140px;\" data-original-width=\"720\" data-original-height=\"140\" > <div class=\"gallery-group images-1\" style=\"width: 186px; height: 140px;\" data-original-width=\"186\" data-original-height=\"140\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/chiomedoro_giona_29\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"182\"> <meta itemprop=\"height\" content=\"136\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"389\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_29.jpg\" data-orig-size=\"1600,1200\" data-comments-opened=\"\" data-image-title=\"ChiomeDOro_Giona_29\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_29.jpg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_29.jpg?fit=720%2C540&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_29.jpg?w=182&#038;h=136&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_29.jpg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_29.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_29.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_29.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_29.jpg?w=1440&amp;ssl=1 1440w\" width=\"182\" height=\"136\" loading=\"lazy\" data-original-width=\"182\" data-original-height=\"136\" itemprop=\"http:\/\/schema.org\/image\" title=\"ChiomeDOro_Giona_29\" alt=\"\u00a9B.Archinard\" style=\"width: 182px; height: 136px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> \u00a9B.Archinard <\/div> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 115px; height: 140px;\" data-original-width=\"115\" data-original-height=\"140\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/chiomedoro_giona_27\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"111\"> <meta itemprop=\"height\" content=\"136\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"387\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_27.jpg\" data-orig-size=\"1303,1600\" data-comments-opened=\"\" data-image-title=\"ChiomeDOro_Giona_27\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_27.jpg?fit=244%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_27.jpg?fit=720%2C884&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_27.jpg?w=111&#038;h=136&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_27.jpg?w=1303&amp;ssl=1 1303w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_27.jpg?resize=244%2C300&amp;ssl=1 244w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_27.jpg?resize=768%2C943&amp;ssl=1 768w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_27.jpg?resize=834%2C1024&amp;ssl=1 834w\" width=\"111\" height=\"136\" loading=\"lazy\" data-original-width=\"111\" data-original-height=\"136\" itemprop=\"http:\/\/schema.org\/image\" title=\"ChiomeDOro_Giona_27\" alt=\"ChiomeDOro_Giona_27\" style=\"width: 111px; height: 136px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 210px; height: 140px;\" data-original-width=\"210\" data-original-height=\"140\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/index.php\/medias\/photos\/giona\/_dsc6506_chiome_doro_giona_fest_amb_01102016__bertrand_pichene-ccr_ambronay\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"206\"> <meta itemprop=\"height\" content=\"136\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"766\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/12\/DSC6506_Chiome_dOro_Giona_Fest_Amb_01102016_\u00a9_Bertrand_PICHENE-CCR_Ambronay.jpg\" data-orig-size=\"4839,3205\" data-comments-opened=\"1\" data-image-title=\"_DSC6506_Chiome_dOro_Giona_Fest_Amb_01102016_\u00a9_Bertrand_PICHENE-CCR_Ambronay\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/12\/DSC6506_Chiome_dOro_Giona_Fest_Amb_01102016_%C2%A9_Bertrand_PICHENE-CCR_Ambronay.jpg?fit=300%2C199&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/12\/DSC6506_Chiome_dOro_Giona_Fest_Amb_01102016_%C2%A9_Bertrand_PICHENE-CCR_Ambronay.jpg?fit=720%2C477&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/12\/DSC6506_Chiome_dOro_Giona_Fest_Amb_01102016_%C2%A9_Bertrand_PICHENE-CCR_Ambronay.jpg?w=206&#038;h=136&#038;ssl=1\" width=\"206\" height=\"136\" loading=\"lazy\" data-original-width=\"206\" data-original-height=\"136\" itemprop=\"http:\/\/schema.org\/image\" title=\"_DSC6506_Chiome_dOro_Giona_Fest_Amb_01102016_\u00a9_Bertrand_PICHENE-CCR_Ambronay\" alt=\"Ambronay 2016 \u00a9Bertrand Pich\u00e8ne\" style=\"width: 206px; height: 136px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> Ambronay 2016 \u00a9Bertrand Pich\u00e8ne <\/div> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 209px; height: 140px;\" data-original-width=\"209\" data-original-height=\"140\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/chiomedoro.com\/chiomedoro_giona_20\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"205\"> <meta itemprop=\"height\" content=\"136\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"380\" data-orig-file=\"https:\/\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_20.jpg\" data-orig-size=\"640,426\" data-comments-opened=\"\" data-image-title=\"ChiomeDOro_Giona_20\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_20.jpg?fit=300%2C200&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_20.jpg?fit=640%2C426&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_20.jpg?w=205&#038;h=136&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_20.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/chiomedoro.com\/wp-content\/uploads\/2017\/10\/ChiomeDOro_Giona_20.jpg?resize=300%2C200&amp;ssl=1 300w\" width=\"205\" height=\"136\" loading=\"lazy\" data-original-width=\"205\" data-original-height=\"136\" itemprop=\"http:\/\/schema.org\/image\" title=\"ChiomeDOro_Giona_20\" alt=\"ChiomeDOro_Giona_20\" style=\"width: 205px; height: 136px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":356,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/no-sidebar.php","meta":{"footnotes":""},"class_list":["post-422","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/P9gKRr-6O","jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/chiomedoro.com\/index.php\/wp-json\/wp\/v2\/pages\/422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chiomedoro.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/chiomedoro.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/chiomedoro.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chiomedoro.com\/index.php\/wp-json\/wp\/v2\/comments?post=422"}],"version-history":[{"count":6,"href":"https:\/\/chiomedoro.com\/index.php\/wp-json\/wp\/v2\/pages\/422\/revisions"}],"predecessor-version":[{"id":789,"href":"https:\/\/chiomedoro.com\/index.php\/wp-json\/wp\/v2\/pages\/422\/revisions\/789"}],"up":[{"embeddable":true,"href":"https:\/\/chiomedoro.com\/index.php\/wp-json\/wp\/v2\/pages\/356"}],"wp:attachment":[{"href":"https:\/\/chiomedoro.com\/index.php\/wp-json\/wp\/v2\/media?parent=422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}